{"id":5789,"date":"2024-06-07T09:18:27","date_gmt":"2024-06-07T09:18:27","guid":{"rendered":"https:\/\/www.ca-autofinance.ch\/esg\/"},"modified":"2024-06-11T12:39:57","modified_gmt":"2024-06-11T12:39:57","slug":"esg","status":"publish","type":"page","link":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/","title":{"rendered":"ESG"},"content":{"rendered":"\n        <div\n            id=\"block_4e179118-9bbe-425d-9b5c-6153fddeef8b\"\n            class=\"wp-block internal-header-block \"\n                    >\n\n        <h1><strong>ESG<\/strong><br \/>\nENVIRONMENT, SOCIAL, GOVERNANCE.<\/h1>\n    <div class=\"cms-txt\"><p>Il nostro Purpose \u00e8 \u201cCreiamo ogni giorno soluzioni di mobilit\u00e0 per un pianeta migliore\u201d. Riassume la nostra ragion d\u2019essere: guidare la transizione verso una mobilit\u00e0 sostenibile, attraverso le soluzioni finanziarie promosse dalla Banca e la gamma di soluzioni di mobilit\u00e0 di Drivalia.<\/p>\n<\/div>\n\n\n        <\/div>\n    \n\n\n\n\n        <div\n            id=\"block_01625a31-0993-491b-ae96-ef1c68d8bb92\"\n            class=\"wp-block image-block \"\n                    >\n\n        \n<figure>\n            <img decoding=\"async\" src=\"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2024\/06\/768x465_desk_Sostenibilita_ESG.webp\"\n             alt=\"\">\n        <figcaption><\/figcaption>\n<\/figure>\n\n\n        <\/div>\n    \n\n\n\n\n        <div\n            id=\"block_2172e3b2-4b18-436c-a856-93aa38087586\"\n            class=\"wp-block rich-text-block rich-text-block-bg-transparent \"\n                    >\n\n        \n<div class=\"cms-txt\"><p>La nostra identit\u00e0 ESG poggia su quattro Pilastri: Mobilit\u00e0 Sostenibile, Innovazione e Digitalizzazione, Persone e Ambiente. Essi costituiscono il nostro framework di sostenibilit\u00e0 e orientano i nostri processi nella creazione di valore verso i nostri stakeholder.<\/p>\n<\/div>\n\n\n        <\/div>\n    \n        <div\n            id=\"block_83f79f9e-f9fa-45d7-9875-099d12a62013\"\n            class=\"wp-block rich-text-block rich-text-block-bg-transparent \"\n                    >\n\n        \n<div class=\"cms-txt\"><h2>I NOSTRI PILASTRI ESG<\/h2>\n<p><strong>La Mobilit\u00e0<\/strong> <strong>Sostenibile<\/strong> \u00e8 il driver di innovazione del nostro modello di business. Promuoviamo soluzioni finanziarie innovative per rendere la mobilit\u00e0 sostenibile alla portata di tutti i clienti. Insieme a Drivalia, guidiamo la transizione elettrica attraverso formule di mobilit\u00e0 flessibili e una strategia di elettrificazione volta allo sviluppo di infrastrutture di ricarica elettrica in tutta Europa.<\/p>\n<p>I nostri comportamenti responsabili verso l\u2019<strong>Ambiente<\/strong> si concretizzano nell\u2019impegno a ridurre l\u2019impronta di carbonio, nell\u2019essere una banca completamente digitale e nel favorire la transizione dei nostri clienti verso una mobilit\u00e0 pi\u00f9 sostenibile.<\/p>\n<p>Il nostro successo di basa sulle <strong>Persone<\/strong>: i nostri dipendenti e i nostri clienti. Ci prendiamo cura dei nostri primi stakeholder, i dipendenti, investendo su di loro per garantire un corretto equilibrio tra lavoro e vita privata. Allo stesso tempo siamo partner di fiducia per i nostri clienti, mettendo al centro le loro esigenze.<\/p>\n<p>Siamo una banca innovativa e digitale. Grazie all\u2019Innovazione e alla Digitalizzazione garantiamo la massima accessibilit\u00e0 e trasparenza dei nostri servizi.<\/p>\n<\/div>\n\n\n        <\/div>\n    \n        <div\n            id=\"block_05ffbe28-a3a4-4e6d-a5f7-c3d0aa4437d8\"\n            class=\"wp-block spacer-block \"\n                    >\n\n        \n<div class=\"spacer-50\"><\/div>\n\n\n        <\/div>\n    \n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":0,"parent":5791,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-innerpage.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-5789","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ESG - CA Auto Finance Suisse SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESG - CA Auto Finance Suisse SA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/\" \/>\n<meta property=\"og:site_name\" content=\"CA Auto Finance Suisse SA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T12:39:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/\",\"url\":\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/\",\"name\":\"ESG - CA Auto Finance Suisse SA\",\"isPartOf\":{\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#website\"},\"datePublished\":\"2024-06-07T09:18:27+00:00\",\"dateModified\":\"2024-06-11T12:39:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ca-autofinance.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sostenibilit\u00e0\",\"item\":\"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#website\",\"url\":\"https:\/\/www.ca-autofinance.ch\/it\/\",\"name\":\"CA Auto Finance Suisse SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ca-autofinance.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#organization\",\"name\":\"CA Auto Finance Suisse SA\",\"url\":\"https:\/\/www.ca-autofinance.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_696x696.png\",\"contentUrl\":\"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"CA Auto Finance Suisse SA\"},\"image\":{\"@id\":\"https:\/\/www.ca-autofinance.ch\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESG - CA Auto Finance Suisse SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/","og_locale":"it_IT","og_type":"article","og_title":"ESG - CA Auto Finance Suisse SA","og_url":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/","og_site_name":"CA Auto Finance Suisse SA","article_modified_time":"2024-06-11T12:39:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_1200x675.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/","url":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/","name":"ESG - CA Auto Finance Suisse SA","isPartOf":{"@id":"https:\/\/www.ca-autofinance.ch\/it\/#website"},"datePublished":"2024-06-07T09:18:27+00:00","dateModified":"2024-06-11T12:39:57+00:00","breadcrumb":{"@id":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ca-autofinance.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Sostenibilit\u00e0","item":"https:\/\/www.ca-autofinance.ch\/it\/sostenibilita\/"},{"@type":"ListItem","position":3,"name":"ESG"}]},{"@type":"WebSite","@id":"https:\/\/www.ca-autofinance.ch\/it\/#website","url":"https:\/\/www.ca-autofinance.ch\/it\/","name":"CA Auto Finance Suisse SA","description":"","publisher":{"@id":"https:\/\/www.ca-autofinance.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ca-autofinance.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ca-autofinance.ch\/it\/#organization","name":"CA Auto Finance Suisse SA","url":"https:\/\/www.ca-autofinance.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ca-autofinance.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_696x696.png","contentUrl":"https:\/\/www.ca-autofinance.ch\/wp-content\/uploads\/sites\/14\/2023\/04\/LOGO-CA-AUTO-FINANCE_696x696.png","width":696,"height":696,"caption":"CA Auto Finance Suisse SA"},"image":{"@id":"https:\/\/www.ca-autofinance.ch\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/pages\/5789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/comments?post=5789"}],"version-history":[{"count":2,"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/pages\/5789\/revisions"}],"predecessor-version":[{"id":5839,"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/pages\/5789\/revisions\/5839"}],"up":[{"embeddable":true,"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/pages\/5791"}],"wp:attachment":[{"href":"https:\/\/www.ca-autofinance.ch\/it\/wp-json\/wp\/v2\/media?parent=5789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}